{"id":6513,"date":"2023-03-14T23:08:16","date_gmt":"2023-03-14T23:08:16","guid":{"rendered":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/"},"modified":"2023-03-14T23:09:18","modified_gmt":"2023-03-14T23:09:18","slug":"minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641","status":"publish","type":"product","link":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/","title":{"rendered":"Minka Lavery Tofino 28 Inch Wall Sconce Tofino &#8211; 6765-211 &#8211; Transitional- 1168641"},"content":{"rendered":"<p>Minka Lavery Tofino 28 Inch Wall Sconce Tofino Wall Sconce by Minka Lavery &#8211; 6765-211<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Minka Lavery Tofino 28 Inch Wall Sconce Tofino Wall Sconce by Minka Lavery &#8211; 6765-211<\/p>\n","protected":false},"featured_media":6514,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[60,61,62,70],"product_tag":[73],"class_list":["post-6513","product","type-product","status-publish","has-post-thumbnail","product_cat-home-garden","product_cat-lighting","product_cat-lighting-fixtures","product_cat-wall-light-fixtures","product_tag-minka-lavery","first","instock","product-type-external"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Minka Lavery Tofino 28 Inch Wall Sconce Tofino - 6765-211 - Transitional<\/title>\n<meta name=\"description\" content=\"Minka Lavery Tofino 28 Inch Wall Sconce Tofino - 6765-211 - Transitional - Minka Lavery Tofino 28 Inch Wall Sconce Tofino Wall Sconce by Minka Lavery - 6765-211\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minka Lavery Tofino 28 Inch Wall Sconce Tofino - 6765-211 - Transitional - Minka Lavery Tofino 28 Inch Wall Sconce Tofino Wall Sconce by Minka Lavery - 6765-211\" \/>\n<meta property=\"og:description\" content=\"Minka Lavery Tofino 28 Inch Wall Sconce Tofino - 6765-211 - Transitional - Minka Lavery Tofino 28 Inch Wall Sconce Tofino Wall Sconce by Minka Lavery - 6765-211\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/\" \/>\n<meta property=\"og:site_name\" content=\"Lighting and Accessories\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-14T23:09:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/wp-content\/uploads\/2023\/03\/Minka-Lavery_6765-211.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1879\" \/>\n\t<meta property=\"og:image:height\" content=\"1879\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Minka Lavery Tofino 28 Inch Wall Sconce Tofino - 6765-211 - Transitional - Minka Lavery Tofino 28 Inch Wall Sconce Tofino Wall Sconce by Minka Lavery - 6765-211\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/\",\"url\":\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/\",\"name\":\"Minka Lavery Tofino 28 Inch Wall Sconce Tofino - 6765-211 - Transitional\",\"isPartOf\":{\"@id\":\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/wp-content\/uploads\/2023\/03\/Minka-Lavery_6765-211.jpg\",\"datePublished\":\"2023-03-14T23:08:16+00:00\",\"dateModified\":\"2023-03-14T23:09:18+00:00\",\"description\":\"Minka Lavery Tofino 28 Inch Wall Sconce Tofino - 6765-211 - Transitional - Minka Lavery Tofino 28 Inch Wall Sconce Tofino Wall Sconce by Minka Lavery - 6765-211\",\"breadcrumb\":{\"@id\":\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/#primaryimage\",\"url\":\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/wp-content\/uploads\/2023\/03\/Minka-Lavery_6765-211.jpg\",\"contentUrl\":\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/wp-content\/uploads\/2023\/03\/Minka-Lavery_6765-211.jpg\",\"width\":1879,\"height\":1879},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Minka Lavery Tofino 28 Inch Wall Sconce Tofino &#8211; 6765-211 &#8211; Transitional- 1168641\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/#website\",\"url\":\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/\",\"name\":\"Lighting and Accessories\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mostincrediblevalue.com\/capitol-lighting\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Minka Lavery Tofino 28 Inch Wall Sconce Tofino - 6765-211 - Transitional","description":"Minka Lavery Tofino 28 Inch Wall Sconce Tofino - 6765-211 - Transitional - Minka Lavery Tofino 28 Inch Wall Sconce Tofino Wall Sconce by Minka Lavery - 6765-211","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/","og_locale":"en_US","og_type":"article","og_title":"Minka Lavery Tofino 28 Inch Wall Sconce Tofino - 6765-211 - Transitional - Minka Lavery Tofino 28 Inch Wall Sconce Tofino Wall Sconce by Minka Lavery - 6765-211","og_description":"Minka Lavery Tofino 28 Inch Wall Sconce Tofino - 6765-211 - Transitional - Minka Lavery Tofino 28 Inch Wall Sconce Tofino Wall Sconce by Minka Lavery - 6765-211","og_url":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/","og_site_name":"Lighting and Accessories","article_modified_time":"2023-03-14T23:09:18+00:00","og_image":[{"width":1879,"height":1879,"url":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/wp-content\/uploads\/2023\/03\/Minka-Lavery_6765-211.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Minka Lavery Tofino 28 Inch Wall Sconce Tofino - 6765-211 - Transitional - Minka Lavery Tofino 28 Inch Wall Sconce Tofino Wall Sconce by Minka Lavery - 6765-211","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/","url":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/","name":"Minka Lavery Tofino 28 Inch Wall Sconce Tofino - 6765-211 - Transitional","isPartOf":{"@id":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/#primaryimage"},"image":{"@id":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/#primaryimage"},"thumbnailUrl":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/wp-content\/uploads\/2023\/03\/Minka-Lavery_6765-211.jpg","datePublished":"2023-03-14T23:08:16+00:00","dateModified":"2023-03-14T23:09:18+00:00","description":"Minka Lavery Tofino 28 Inch Wall Sconce Tofino - 6765-211 - Transitional - Minka Lavery Tofino 28 Inch Wall Sconce Tofino Wall Sconce by Minka Lavery - 6765-211","breadcrumb":{"@id":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/#primaryimage","url":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/wp-content\/uploads\/2023\/03\/Minka-Lavery_6765-211.jpg","contentUrl":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/wp-content\/uploads\/2023\/03\/Minka-Lavery_6765-211.jpg","width":1879,"height":1879},{"@type":"BreadcrumbList","@id":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/product\/minka-lavery-tofino-28-inch-wall-sconce-tofino-6765-211-transitional-1168641\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/"},{"@type":"ListItem","position":3,"name":"Minka Lavery Tofino 28 Inch Wall Sconce Tofino &#8211; 6765-211 &#8211; Transitional- 1168641"}]},{"@type":"WebSite","@id":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/#website","url":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/","name":"Lighting and Accessories","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/wp-json\/wp\/v2\/product\/6513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/wp-json\/wp\/v2\/comments?post=6513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/wp-json\/wp\/v2\/media\/6514"}],"wp:attachment":[{"href":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/wp-json\/wp\/v2\/media?parent=6513"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/wp-json\/wp\/v2\/product_cat?post=6513"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mostincrediblevalue.com\/capitol-lighting\/index.php\/wp-json\/wp\/v2\/product_tag?post=6513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}