{"id":17857,"date":"2023-11-22T11:54:57","date_gmt":"2023-11-22T11:54:57","guid":{"rendered":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\/"},"modified":"2023-11-27T21:56:20","modified_gmt":"2023-11-27T21:56:20","slug":"bloomingdales-mogul-m1403-area-rug-61-x-94-4255158","status":"publish","type":"product","link":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\/","title":{"rendered":"Bloomingdale&#8217;s Mogul M1403 Area Rug, 6&#8217;1 x 9&#8217;4- 4255158"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Bloomingdale&#8217;s Mogul M1403 Area Rug, 6&#8217;1 x 9&#8217;4<\/p>\n","protected":false},"featured_media":17858,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[15],"product_tag":[69],"class_list":["post-17857","product","type-product","status-publish","has-post-thumbnail","product_cat-uncategorized","product_tag-bloomingdales","first","instock","product-type-external"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bloomingdale&#039;s Mogul M1403 Area Rug, 6&#039;1 x 9&#039;4<\/title>\n<meta name=\"description\" content=\"Bloomingdale&#039;s Mogul M1403 Area Rug, 6&#039;1 x 9&#039;4 - Bloomingdale&#039;s Mogul M1403 Area Rug, 6&#039;1 x 9&#039;4\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bloomingdale&#039;s Mogul M1403 Area Rug, 6&#039;1 x 9&#039;4\" \/>\n<meta property=\"og:description\" content=\"Bloomingdale&#039;s Mogul M1403 Area Rug, 6&#039;1 x 9&#039;4 - Bloomingdale&#039;s Mogul M1403 Area Rug, 6&#039;1 x 9&#039;4\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\/\" \/>\n<meta property=\"og:site_name\" content=\"Home &amp; Garden\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-27T21:56:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mostincrediblevalue.com\/home\/wp-content\/uploads\/2023\/11\/11944958_fpx.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/index.php\\\/product\\\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\\\/\",\"url\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/index.php\\\/product\\\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\\\/\",\"name\":\"Bloomingdale's Mogul M1403 Area Rug, 6'1 x 9'4\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/index.php\\\/product\\\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/index.php\\\/product\\\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/11944958_fpx.jpg\",\"datePublished\":\"2023-11-22T11:54:57+00:00\",\"dateModified\":\"2023-11-27T21:56:20+00:00\",\"description\":\"Bloomingdale's Mogul M1403 Area Rug, 6'1 x 9'4 - Bloomingdale's Mogul M1403 Area Rug, 6'1 x 9'4\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/index.php\\\/product\\\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/index.php\\\/product\\\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/index.php\\\/product\\\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/11944958_fpx.jpg\",\"contentUrl\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/11944958_fpx.jpg\",\"width\":300,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/index.php\\\/product\\\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bloomingdale&#8217;s Mogul M1403 Area Rug, 6&#8217;1 x 9&#8217;4- 4255158\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/\",\"name\":\"Home &amp; Garden\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bloomingdale's Mogul M1403 Area Rug, 6'1 x 9'4","description":"Bloomingdale's Mogul M1403 Area Rug, 6'1 x 9'4 - Bloomingdale's Mogul M1403 Area Rug, 6'1 x 9'4","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\/","og_locale":"en_US","og_type":"article","og_title":"Bloomingdale's Mogul M1403 Area Rug, 6'1 x 9'4","og_description":"Bloomingdale's Mogul M1403 Area Rug, 6'1 x 9'4 - Bloomingdale's Mogul M1403 Area Rug, 6'1 x 9'4","og_url":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\/","og_site_name":"Home &amp; Garden","article_modified_time":"2023-11-27T21:56:20+00:00","og_image":[{"width":300,"height":375,"url":"https:\/\/mostincrediblevalue.com\/home\/wp-content\/uploads\/2023\/11\/11944958_fpx.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\/","url":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\/","name":"Bloomingdale's Mogul M1403 Area Rug, 6'1 x 9'4","isPartOf":{"@id":"https:\/\/mostincrediblevalue.com\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\/#primaryimage"},"image":{"@id":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\/#primaryimage"},"thumbnailUrl":"https:\/\/mostincrediblevalue.com\/home\/wp-content\/uploads\/2023\/11\/11944958_fpx.jpg","datePublished":"2023-11-22T11:54:57+00:00","dateModified":"2023-11-27T21:56:20+00:00","description":"Bloomingdale's Mogul M1403 Area Rug, 6'1 x 9'4 - Bloomingdale's Mogul M1403 Area Rug, 6'1 x 9'4","breadcrumb":{"@id":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\/#primaryimage","url":"https:\/\/mostincrediblevalue.com\/home\/wp-content\/uploads\/2023\/11\/11944958_fpx.jpg","contentUrl":"https:\/\/mostincrediblevalue.com\/home\/wp-content\/uploads\/2023\/11\/11944958_fpx.jpg","width":300,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/bloomingdales-mogul-m1403-area-rug-61-x-94-4255158\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mostincrediblevalue.com\/home\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/mostincrediblevalue.com\/home\/"},{"@type":"ListItem","position":3,"name":"Bloomingdale&#8217;s Mogul M1403 Area Rug, 6&#8217;1 x 9&#8217;4- 4255158"}]},{"@type":"WebSite","@id":"https:\/\/mostincrediblevalue.com\/home\/#website","url":"https:\/\/mostincrediblevalue.com\/home\/","name":"Home &amp; Garden","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mostincrediblevalue.com\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/mostincrediblevalue.com\/home\/index.php\/wp-json\/wp\/v2\/product\/17857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mostincrediblevalue.com\/home\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mostincrediblevalue.com\/home\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mostincrediblevalue.com\/home\/index.php\/wp-json\/wp\/v2\/comments?post=17857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mostincrediblevalue.com\/home\/index.php\/wp-json\/wp\/v2\/media\/17858"}],"wp:attachment":[{"href":"https:\/\/mostincrediblevalue.com\/home\/index.php\/wp-json\/wp\/v2\/media?parent=17857"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mostincrediblevalue.com\/home\/index.php\/wp-json\/wp\/v2\/product_brand?post=17857"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mostincrediblevalue.com\/home\/index.php\/wp-json\/wp\/v2\/product_cat?post=17857"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mostincrediblevalue.com\/home\/index.php\/wp-json\/wp\/v2\/product_tag?post=17857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}