{"id":47529,"date":"2025-02-12T06:08:02","date_gmt":"2025-02-12T06:08:02","guid":{"rendered":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/labrazel-biella-canister\/"},"modified":"2025-02-12T06:08:11","modified_gmt":"2025-02-12T06:08:11","slug":"labrazel-biella-canister","status":"publish","type":"product","link":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/labrazel-biella-canister\/","title":{"rendered":"Labrazel Biella Canister"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Labrazel Biella Canister.Color:White Pearl.Material:Blown glass.<\/p>\n","protected":false},"featured_media":47530,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[353],"product_tag":[354],"class_list":{"0":"post-47529","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-home-bath_accessories","7":"product_tag-home-bath_accessories","9":"first","10":"instock","11":"product-type-external"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Labrazel Biella Canister<\/title>\n<meta name=\"description\" content=\"Labrazel Biella Canister - Labrazel Biella Canister.Color:White Pearl.Material:Blown glass.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/labrazel-biella-canister\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Labrazel Biella Canister\" \/>\n<meta property=\"og:description\" content=\"Labrazel Biella Canister - Labrazel Biella Canister.Color:White Pearl.Material:Blown glass.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/labrazel-biella-canister\/\" \/>\n<meta property=\"og:site_name\" content=\"Home &amp; Garden\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-12T06:08:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mostincrediblevalue.com\/home\/wp-content\/uploads\/2025\/02\/10577652_fpx.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/index.php\\\/product\\\/labrazel-biella-canister\\\/\",\"url\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/index.php\\\/product\\\/labrazel-biella-canister\\\/\",\"name\":\"Labrazel Biella Canister\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/index.php\\\/product\\\/labrazel-biella-canister\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/index.php\\\/product\\\/labrazel-biella-canister\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/10577652_fpx.jpg\",\"datePublished\":\"2025-02-12T06:08:02+00:00\",\"dateModified\":\"2025-02-12T06:08:11+00:00\",\"description\":\"Labrazel Biella Canister - Labrazel Biella Canister.Color:White Pearl.Material:Blown glass.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/index.php\\\/product\\\/labrazel-biella-canister\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/index.php\\\/product\\\/labrazel-biella-canister\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/index.php\\\/product\\\/labrazel-biella-canister\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/10577652_fpx.jpg\",\"contentUrl\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/10577652_fpx.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/index.php\\\/product\\\/labrazel-biella-canister\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Labrazel Biella Canister\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/\",\"name\":\"Home &amp; Garden\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mostincrediblevalue.com\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Labrazel Biella Canister","description":"Labrazel Biella Canister - Labrazel Biella Canister.Color:White Pearl.Material:Blown glass.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/labrazel-biella-canister\/","og_locale":"en_US","og_type":"article","og_title":"Labrazel Biella Canister","og_description":"Labrazel Biella Canister - Labrazel Biella Canister.Color:White Pearl.Material:Blown glass.","og_url":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/labrazel-biella-canister\/","og_site_name":"Home &amp; Garden","article_modified_time":"2025-02-12T06:08:11+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/mostincrediblevalue.com\/home\/wp-content\/uploads\/2025\/02\/10577652_fpx.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/labrazel-biella-canister\/","url":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/labrazel-biella-canister\/","name":"Labrazel Biella Canister","isPartOf":{"@id":"https:\/\/mostincrediblevalue.com\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/labrazel-biella-canister\/#primaryimage"},"image":{"@id":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/labrazel-biella-canister\/#primaryimage"},"thumbnailUrl":"https:\/\/mostincrediblevalue.com\/home\/wp-content\/uploads\/2025\/02\/10577652_fpx.jpg","datePublished":"2025-02-12T06:08:02+00:00","dateModified":"2025-02-12T06:08:11+00:00","description":"Labrazel Biella Canister - Labrazel Biella Canister.Color:White Pearl.Material:Blown glass.","breadcrumb":{"@id":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/labrazel-biella-canister\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/labrazel-biella-canister\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/labrazel-biella-canister\/#primaryimage","url":"https:\/\/mostincrediblevalue.com\/home\/wp-content\/uploads\/2025\/02\/10577652_fpx.jpg","contentUrl":"https:\/\/mostincrediblevalue.com\/home\/wp-content\/uploads\/2025\/02\/10577652_fpx.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/mostincrediblevalue.com\/home\/index.php\/product\/labrazel-biella-canister\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mostincrediblevalue.com\/home\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/mostincrediblevalue.com\/home\/"},{"@type":"ListItem","position":3,"name":"Labrazel Biella Canister"}]},{"@type":"WebSite","@id":"https:\/\/mostincrediblevalue.com\/home\/#website","url":"https:\/\/mostincrediblevalue.com\/home\/","name":"Home &amp; Garden","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mostincrediblevalue.com\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/mostincrediblevalue.com\/home\/index.php\/wp-json\/wp\/v2\/product\/47529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mostincrediblevalue.com\/home\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mostincrediblevalue.com\/home\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mostincrediblevalue.com\/home\/index.php\/wp-json\/wp\/v2\/comments?post=47529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mostincrediblevalue.com\/home\/index.php\/wp-json\/wp\/v2\/media\/47530"}],"wp:attachment":[{"href":"https:\/\/mostincrediblevalue.com\/home\/index.php\/wp-json\/wp\/v2\/media?parent=47529"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mostincrediblevalue.com\/home\/index.php\/wp-json\/wp\/v2\/product_brand?post=47529"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mostincrediblevalue.com\/home\/index.php\/wp-json\/wp\/v2\/product_cat?post=47529"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mostincrediblevalue.com\/home\/index.php\/wp-json\/wp\/v2\/product_tag?post=47529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}